{"id":7635,"date":"2022-08-15T18:19:44","date_gmt":"2022-08-15T18:19:44","guid":{"rendered":"https:\/\/www.aspartyrental.com\/lexington\/inventory\/wedding-package\/bistro-wood-top-table-setup-not-included\/"},"modified":"2026-08-04T22:00:38","modified_gmt":"2026-08-04T22:00:38","slug":"bistro-wood-top-table-setup-not-included","status":"publish","type":"page","link":"https:\/\/www.aspartyrental.com\/lexington\/inventory\/wedding-package\/bistro-wood-top-table-setup-not-included\/","title":{"rendered":"30&#8243; Bistro Wood Table (Setup not Included)"},"content":{"rendered":"<!-- Start Shortcoder content --><div class=\"io_product_container elementor-widget-text-editor io_product_container_1261261:370522\">\n  <!-- Cart -->\n  <div class=\"cartInfo\" style=\"display:none\">\n    <i class=\"cartIcon fas fa-shopping-cart\"><\/i><!--no linebreak bc elementor--> <span class=\"simpleCart_quantity\"><\/span> items\n  <\/div>\n\n  <!-- Page Content -->\n  <div class=\"simpleCart_ioShelfItem\">\n    <div class=\"io_product_picbox\">\n      <div id=\"io_main_media_container\">\n        <a rel=\"img_group noopener\" id=\"single_image\" href=\"https:\/\/www.aspartyrental.com\/lexington\/wp-content\/uploads\/sites\/5\/2023\/08\/20Edited201_1677612537_big.png\">\n          <img decoding=\"async\" class=\"io_image_big item_image\" title=\"30 Bistro Wood Table (Setup not Included)\" src=\"https:\/\/www.aspartyrental.com\/lexington\/wp-content\/uploads\/sites\/5\/2023\/08\/20Edited201_1677612537_big.png\" alt=\"30 Bistro Wood Table (Setup not Included)\" \/>\n        <\/a>\n        <video class=\"io_video_big\" id=\"io_main_video\" controls preload=\"none\" style=\"max-width:100%;\" playsinline>\n          <source src=\"\" type=\"video\/mp4\">\n        <\/video>\n      <\/div>\n      <br>\n      <div class=\"io_image_thumbbox\" id=\"io_media_thumbbox\">\n        <!-- Thumbnails built dynamically by JS from images_arr -->\n      <\/div>\n    <\/div>\n    <div class=\"io_product_infobox\">\n      <div class=\"elementor-widget-heading\">\n        <h1 class=\"io_product_title elementor-heading-title item_name\">30\" Bistro Wood Table (Setup not Included)<\/h1>\n      <\/div>\n\n      <p class=\"item_encoded\" style=\"display:none;\">30%22+Bistro+Wood+Table+%28Setup+not+Included%29<\/p>\n      <p class=\"item_rentalid\" style=\"display:none;\">1261261:370522<\/p>\n      <p class=\"item_quantity\" style=\"display:none;\">1<\/p>\n      <p class=\"item_vendorid\" style=\"display:none;\"><\/p>\n      <p class=\"item_qtytype\" style=\"display:none;\">Limited<\/p>\n      <p class=\"item_inputtype\" style=\"display:none;\">Dropdown<\/p>\n      <span class=\"item_qtyincrement\" style=\"display:none;\">1<\/span>\n      <div class=\"item_timeslots\" style=\"display:none;\"><\/div>\n      <p class=\"item_giftcardvalue\" style=\"display:none;\"><\/p>\n      <div class=\"io_star_rating\">\n        <div class=\"io_stars_1261261:370522 io_stars\"><\/div>\n        <a href=\"#page_product_reviews\">See Reviews<\/a>\n      <\/div>\n      <div id=\"item_live_price_time_set_message\" style=\"display:none\">\n        <p>\n                                <span style=\"cursor:pointer; color:blue; text-decoration:underline;\" onclick=checkAvailDateClick()>\n                                    click here\n                                <\/span>\n          to set an event time so you can see a more accurate price for this item\n        <\/p>\n      <\/div>\n      <div id=\"item_additonal_info_open_message\" style=\"display:none\">\n        <p>\n                                <span style=\"cursor:pointer; color:blue; text-decoration:underline;\" onclick=checkAvailDateClick()>\n                                    click here\n                                <\/span>\n          to provide information required for pricing.\n        <\/p>\n      <\/div>\n      <div id=\"io_all_prices\">\n        <div class=\"io_product_price_box io_product_price_1h io_product_price_1h_1261261:370522\">\n          <p class=\"io_product_price_top_left\">$15.00<\/p>\n          <p class=\"io_product_price_top_right\">per hour<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_2h io_product_price_2h_1261261:370522\">\n          <p class=\"io_product_price_top_left\">$15.00<\/p>\n          <p class=\"io_product_price_top_right\">for 2 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_3h io_product_price_3h_1261261:370522\">\n          <p class=\"io_product_price_top_left\">$15.00<\/p>\n          <p class=\"io_product_price_top_right\">for 3 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_4h io_product_price_4h_1261261:370522\">\n          <p class=\"io_product_price_top_left\">$15.00<\/p>\n          <p class=\"io_product_price_top_right\">for 4 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_5h io_product_price_5h_1261261:370522\">\n          <p class=\"io_product_price_top_left\">$15.00<\/p>\n          <p class=\"io_product_price_top_right\">for 5 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_6h io_product_price_6h_1261261:370522\">\n          <p class=\"io_product_price_top_left\">$15.00<\/p>\n          <p class=\"io_product_price_top_right\">for 6 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_7h io_product_price_7h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 7 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_8h io_product_price_8h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 8 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_9h io_product_price_9h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 9 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_10h io_product_price_10h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 10 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_11h io_product_price_11h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 11 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_12h io_product_price_12h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 12 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_13h io_product_price_13h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 13 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_14h io_product_price_14h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 14 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_15h io_product_price_15h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 15 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_16h io_product_price_16h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 16 hours<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_24h io_product_price_24h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">per day<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_additionalhour io_product_price_additionalhour_1261261:370522\">\n          <p class=\"io_product_price_left\">$0.00<\/p>\n          <p class=\"io_product_price_right\">per additional hour<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_additionalday io_product_price_additionalday_1261261:370522\">\n          <p class=\"io_product_price_left\">$0.00<\/p>\n          <p class=\"io_product_price_right\">per additional day<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_48h io_product_price_48h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 2 days<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_72h io_product_price_72h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 3 days<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_96h io_product_price_96h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 4 days<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_120h io_product_price_120h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 5 days<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_168h io_product_price_168h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 1 week<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_336h io_product_price_336h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 2 weeks<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_504h io_product_price_504h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 3 weeks<\/p>\n        <\/div>\n        <div class=\"io_product_price_box io_product_price_720h io_product_price_720h_1261261:370522\">\n          <p class=\"io_product_price_left\">$15.00<\/p>\n          <p class=\"io_product_price_right\">for 1 month<\/p>\n        <\/div>\n      <\/div>\n      <div class=\"io_product_price_box io_product_price_fixed io_product_price_fixed_1261261:370522\" style=\"display:none\">\n        <p class=\"io_product_price_top_left\">$15.00<\/p>\n        <p class=\"io_product_price_top_right\">per item<\/p>\n      <\/div>\n      <div class=\"io_product_price_box io_product_price_sqfoot io_product_price_sqfoot_1261261:370522\" style=\"display:none\">\n        <p class=\"io_product_price_top_left\">$15.00<\/p>\n        <p class=\"io_product_price_top_right\">per sq foot<\/p>\n      <\/div>\n      <div class=\"io_product_acc_pkg\" style=\"margin-top:14px;\"><\/div>\n      <div class=\"elementor-widget-button io_phrase_1261261:370522\" style=\"display:none;margin-top:25px; \">\n        <label for=\"phraseInput\" style=\"color:darkred\">\n          Enter the phrase you want displayed:\n        <\/label><br>\n        <input\n                type=\"text\"\n                id=\"phraseInput\"\n                class=\"io_phrase_1261261:370522\"\n                style=\"width: 300px;\"\n                oninput=\"phraseUpdateCount(this)\"\n        \/>\n      <\/div>\n      <div style=\"display: inline-flex\">\n        <div>\n          <div class=\"elementor-widget-button add_cart_1261261:370522\">\n            <a id=\"bookNowBtn\"\n               class=\"item_add elementor-button elementor-size-sm elementor-animation-grow io_button\"\n               href=\"javascript:;\"><!--no linebreak bc elementor--><i class=\"fas fa-shopping-cart\"><\/i> Add to Cart<\/a>\n          <\/div>\n          <div class=\"unavailable_message\" onclick=\"checkAvailDateClick()\">item unavailable (change date)<\/div>\n        <\/div>\n        <div class=\"delivery_charge_check_container\">\n          <div class=\"elementor-widget-button check_delivery_1261261:370522\">\n            <a id=\"checkDeliveryButton\"\n               class=\"elementor-button elementor-size-sm elementor-animation-grow io_button\"\n               href=\"javascript:;\" onClick=\"showAddressEntry()\"><i class=\"fas fa-truck\"><\/i> Check Delivery<\/a>\n          <\/div>\n        <\/div>\n        <div class=\"calc_price_with_map_container\">\n          <div class=\"elementor-widget-button calc_price_map_1261261:370522\">\n            <a id=\"calcPriceOpenMap\"\n               class=\"elementor-button elementor-size-sm elementor-animation-grow io_button\"\n               href=\"javascript:;\" onClick=\"openMap(this)\"><i class=\"fas fa-map\"><\/i> Calculate Price <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <div class=\"io_product_detailbox\">\n        <h3 class=\"io_product_subtitle\">Product Information:<\/h3>\n        <div class=\"io_product_desc\"><\/div>\n      <\/div>\n      <div class=\"io_product_detail_box\" style=\"margin-top:40px\">\n        <p class=\"io_product_circuits_left\">Circuits needed:<\/p>\n        <p class=\"io_product_circuits_right\">0<\/p>\n      <\/div>\n      <div class=\"io_product_detail_box\">\n        <p class=\"io_product_dimensions_left\">Item Dimensions:<\/p>\n        <p class=\"io_product_dimensions_right\"><\/p>\n      <\/div>\n      <div class=\"io_product_detail_box\">\n        <p class=\"io_product_footprint_left\">Space Needed:<\/p>\n        <p class=\"io_product_footprint_right\"><\/p>\n      <\/div>\n      <!-- Start Shortcoder content -->\n<div class=\"eh_additional_description\" style=\"display:none\">\n    <ul>\n    <li><strong>DELIVERY:<\/strong> We deliver to Franklin OH and surrounding areas (delivery fees calculated at checkout).<\/li>\n    <li><strong>COUPONS:<\/strong><a href=\"\/coupon-form\/\">Click here to check for coupons.<\/a><\/li>\n    <li><strong>RAIN POLICY:<\/strong> You can reschedule your rental due to rain at no extra cost as long as 24 hour notice is given.<\/li>\n    <li><strong>OCCUPANCY:<\/strong> A maximum of 5-6 kids of equal size at one time for bounce houses, and 1 person at a time for slides is what most inflatable manufacturers recommend.<\/li>\n    <li><strong>CLEANING:<\/strong> All units are cleaned and sanitized before use.<\/li>\n    <li><strong>WHAT'S INCLUDED:<\/strong>\n        <ul class=\"square\">\n        <li>Extension Cord<\/li>\n        <li>Blower<\/li>\n        <li>Safety Stakes to secure to ground<\/li>\n        <\/ul>\n    <\/li>\n    <li><strong>WHAT YOU'LL NEED:<\/strong>\n        <ul class=\"square\">\n        <li>Enough space for us to setup your rental<\/li>\n        <li>Electric outlet within 50 feet of setup area<\/li>\n        <li>Water source and water hose if renting a water slide<\/li>\n        <\/ul>\n    <\/li>    \n    <\/ul>\n<\/div>\n<!-- End Shortcoder content -->\n    <\/div>\n  <\/div>\n  <div class=\"io_product_requiredDD_accessories\" style=\"display:none\">\n    <h3 class=\"io_acc_h3\">Required Accessories:<\/h3>\n    <hr>\n  <\/div>\n  <div class=\"io_product_accessories\">\n    <\/p>\n<h3 class=\"io_acc_h3\">Accessories:<\/h3>\n<p><span class=\"io_acc_accessorydd\" style=\"display:none;\">0<\/span><span class=\"io_acc_accessorylimit\" style=\"display:none;\">0<\/span><span class=\"io_acc_ispackage\" style=\"display:none;\">0<\/span><\/p>\n<ul class=\"io_acc_ul\">\n<li class=\"io_acc_li simpleCart_ioShelfItem\" id=\"io_acc_370522_2577271\"><span class=\"io_acc_li_name\" id=\"io_acc_shortname_370522_2577271\" title=\"\">Bistro Table Leg<\/span><span class=\"item_name\" style=\"display:none;\" id=\"io_acc_itemname_2577271\">30\" Bistro Wood Table (Setup not Included):Bistro Table Leg<\/span><span class=\"item_qtyincrement\" id=\"io_acc_qtyincrement_2577271\" style=\"display:none\">1<\/span><span class=\"item_inputtype\" id=\"io_acc_inputtype_2577271\" style=\"display:none\">Dropdown<\/span><span class=\"item_required\" id=\"io_acc_required_370522_2577271\" style=\"display:none\">1<\/span><span class=\"item_rentalid\" style=\"display:none\">370522_2577271<\/span><span class=\"item_linkqty\" style=\"display:none\">0<\/span><span class=\"item_overrideprice\" id=\"io_acc_overrideprice_370522_2577271\" style=\"display:none\">0<\/span><span class=\"item_accessorylimit\" id=\"io_acc_accessorylimit_370522_2577271\" style=\"display:none;\">0<\/span><span class=\"item_accessorydd\" id=\"io_acc_accessorydd_370522_2577271\" style=\"display:none;\">0<\/span>\n<div class=\"io_acc_li_desc\" id=\"io_acc_desc_370522_2577271\">\n<p style=\"font-family: Tahoma, Geneva, sans-serif;\"><\/p>\n<\/div>\n<\/li>\n<li class=\"io_acc_li simpleCart_ioShelfItem\" id=\"io_acc_2577271_591855\"><a rel=\"img_group noopener\" href=\"https:\/\/rental.software\/users\/reservations@asplayzone\/images\/round-bistro-table_1668009766_big.jpg\" id=\"io_acc_imgbig_2577271_591855\" target=\"_blank\"><image class=\"io_acc_li_img_thumb item_image\"  id=\"iothumb_2577271_591855\" src=\"https:\/\/rental.software\/users\/reservations@asplayzone\/images\/round-bistro-table_1668009766.jpg\" title=\"\" \/><\/a><span class=\"io_acc_li_name\" id=\"io_acc_shortname_2577271_591855\" title=\"\">Bistro Wtt 30\" SHORT pole (center pole only)<\/span><span class=\"item_name\" style=\"display:none;\" id=\"io_acc_itemname_591855\">30\" Bistro Wood Table (Setup not Included):Bistro Wtt 30\" SHORT pole (center pole only)<\/span><span class=\"item_qtyincrement\" id=\"io_acc_qtyincrement_591855\" style=\"display:none\">1<\/span><span class=\"item_inputtype\" id=\"io_acc_inputtype_591855\" style=\"display:none\"><\/span><span class=\"item_required\" id=\"io_acc_required_2577271_591855\" style=\"display:none\">0<\/span><span class=\"item_rentalid\" style=\"display:none\">370522_2577271_591855<\/span><span class=\"item_linkqty\" style=\"display:none\">0<\/span><span class=\"item_overrideprice\" id=\"io_acc_overrideprice_2577271_591855\" style=\"display:none\">0<\/span><span class=\"item_accessorylimit\" id=\"io_acc_accessorylimit_2577271_591855\" style=\"display:none;\">0<\/span><span class=\"item_accessorydd\" id=\"io_acc_accessorydd_2577271_591855\" style=\"display:none;\">0<\/span><\/li>\n<li class=\"io_acc_li simpleCart_ioShelfItem\" id=\"io_acc_2577271_591857\"><span class=\"io_acc_li_name\" id=\"io_acc_shortname_2577271_591857\" title=\"\">42\" Center TALL Pole<\/span><span class=\"item_name\" style=\"display:none;\" id=\"io_acc_itemname_591857\">30\" Bistro Wood Table (Setup not Included):42\" Center TALL Pole<\/span><span class=\"item_qtyincrement\" id=\"io_acc_qtyincrement_591857\" style=\"display:none\">1<\/span><span class=\"item_inputtype\" id=\"io_acc_inputtype_591857\" style=\"display:none\"><\/span><span class=\"item_required\" id=\"io_acc_required_2577271_591857\" style=\"display:none\">0<\/span><span class=\"item_rentalid\" style=\"display:none\">370522_2577271_591857<\/span><span class=\"item_linkqty\" style=\"display:none\">0<\/span><span class=\"item_overrideprice\" id=\"io_acc_overrideprice_2577271_591857\" style=\"display:none\">0<\/span><span class=\"item_accessorylimit\" id=\"io_acc_accessorylimit_2577271_591857\" style=\"display:none;\">0<\/span><span class=\"item_accessorydd\" id=\"io_acc_accessorydd_2577271_591857\" style=\"display:none;\">0<\/span><\/li>\n<\/ul>\n<p>\n  <\/div>\n  <a name=\"page_product_reviews\"><\/a>\n  <div class=\"io_product_reviewbox\">\n    \n  <\/div>\n  <div class=\"io_product_upsell\">\n    <h3 class=\"io_upsell_h3\">You might also be interested in:<\/h3>\n    <div class=\"page-carousel\"><\/div>\n  <\/div>\n  <div class=\"io_landingpages io_landingpages_1261261:370522 elementor-widget-text-editor\">\n    <!-- Start Shortcoder content -->Professional delivery to <span class=\\\"io_city_list\\\">Franklin OH<\/span> and surrounding areas. Please submit a quote or contact us to be sure we service your area.<!-- End Shortcoder content -->\n  <\/div>\n<\/div>\n<script>\n  \/\/stars\n  jQuery(document).ready(function () {\n    for(i=0;i<05;i++){\n      star_html = `<div class=\\\"fas fa-star\\\" style=\\\"color:goldenrod\\\"><\/div>`;\n      jQuery(\".io_stars_1261261:370522\").append(star_html);\n    }\n    var times = getAvailTimes();\n    getUpsellsCall(times[0],times[1],times[2],jQuery(\".io_product_infobox .item_rentalid\").first().text(), updatePageUpsell);\n    acc_obj_relate = order_acc_obj_relate();\n    jQuery(\".io_product_price_top_left\").each(function () {\n      if( !Number( this.textContent.replace(\/[^0-9.-]+\/g,\"\") ) ){\n        jQuery(this.parentElement).hide();\n      }\n    });\n    jQuery(\".io_product_price_left\").each(function () {\n      if( !Number( this.textContent.replace(\/[^0-9.-]+\/g,\"\") ) ){\n        jQuery(this.parentElement).attr(\"style\",\"display:none !important\");\n      }\n    });\n  });\n\n  try{ var acc_obj_relate = JSON.parse('{\"2577271\":{\"591855\":{},\"591857\":{}}} '); }\n  catch{ var acc_obj_relate = {}; }\n\n  try{ var images_arr = JSON.parse('{\"0\":{\"rentalimage_id\":\"833003\",\"rentalimage_createtime\":null,\"rentalimage_modifiedtime\":null,\"rentalimage_itemid\":\"370522\",\"rentalimage_order\":\"0\",\"rentalimage_imageloc\":\"https:\/\/www.aspartyrental.com\/lexington\/wp-content\/uploads\/sites\/5\/2023\/09\/20Edited201_1677612537.png\",\"rentalimage_imagelocbig\":\"https:\/\/www.aspartyrental.com\/lexington\/wp-content\/uploads\/sites\/5\/2023\/08\/20Edited201_1677612537_big.png\",\"media_type\":\"image\"}} '); }\n  catch { var images_arr = {}; }\n\n  try{ var acc_obj_order = JSON.parse('{\"0\":2577271} '); }\n  catch { var acc_obj_order = {}; }\n\n  var rental_name_template = \"30 Bistro Wood Table (Setup not Included)\";\n  var alt_text_template = \"30 Bistro Wood Table (Setup not Included)\";\n\n  function ioRentalMatchVideoToImage()\n  {\n    var $bigImage = jQuery('#single_image .io_image_big');\n    var $mainVideo = jQuery('#io_main_video');\n\n    $mainVideo.css(\n    {\n      width: $bigImage.outerWidth() + 'px',\n      height: $bigImage.outerHeight() + 'px',\n      display: 'block'\n    });\n  }\n  function ioRentalShowVideo(el)\n  {\n    var $el = jQuery(el);\n    var $container = jQuery('#io_main_media_container');\n    var $bigImage = jQuery('#single_image .io_image_big');\n    var $mainVideo = jQuery('#io_main_video');\n\n    var imgHeight = $bigImage.outerHeight();\n    if (imgHeight > 0) {\n      $container.css('min-height', imgHeight + 'px');\n    }\n\n    $mainVideo.find('source').attr('src', $el.data('video-src'));\n\n    if ($mainVideo.length && $mainVideo[0]) {\n      $mainVideo[0].load();\n    }\n\n    $container.addClass('is-video-active');\n  }\n\n  function ioRentalShowImage(el)\n  {\n    var $el = jQuery(el);\n    var $container = jQuery('#io_main_media_container');\n    var $singleImage = jQuery('#single_image');\n    var $bigImage = jQuery('#single_image .io_image_big');\n    var $mainVideo = jQuery('#io_main_video');\n\n    if ($el.data('big'))\n    {\n      $bigImage.attr('src', $el.data('big'));\n      $singleImage.attr('href', $el.data('big'));\n    }\n\n    $container.removeClass('is-video-active');\n\n    if ($mainVideo.length && $mainVideo[0]) {\n      $mainVideo[0].pause();\n      $mainVideo[0].currentTime = 0;\n    }\n  }\n\n  \/\/ Build unified media thumbnails and lightbox links from images_arr\n  jQuery(document).ready(function()\n  {\n    var thumbbox = jQuery('#io_media_thumbbox');\n    if (jQuery.isEmptyObject(images_arr)) return;\n\n    jQuery('#single_image').attr('data-elementor-open-lightbox', 'no');\n\n    \/\/ If first media item is a video, show video player instead of broken image on page load\n    var firstMedia = images_arr[Object.keys(images_arr)[0]];\n    if (firstMedia && firstMedia.media_type === 'video' && firstMedia.rentalimage_imagelocbig)\n    {\n      var mainVideo = jQuery('#io_main_video');\n      mainVideo.find('source').attr('src', firstMedia.rentalimage_imagelocbig);\n      if (mainVideo.length && mainVideo[0]) mainVideo[0].load();\n      jQuery('#io_main_media_container').addClass('is-video-active');\n    }\n\n    var count = 0;\n    for (var key in images_arr)\n    {\n      var media = images_arr[key];\n      count++;\n\n      if (media.media_type === 'video' && media.rentalimage_imagelocbig)\n      {\n        var thumb = jQuery(\n          '<div class=\"io_media_thumb_wrapper io_video_thumb_wrapper\">' +\n            '<img class=\"io_image_thumb io_video_thumb skip-lazy\" ' +\n            'src=\"' + media.rentalimage_imageloc + '\" ' +\n            'data-video-src=\"' + media.rentalimage_imagelocbig + '\" ' +\n            'data-media-type=\"video\" ' +\n            'title=\"' + rental_name_template + '\" ' +\n            'alt=\"' + alt_text_template + '\" ' +\n            'id=\"io_img_thumb' + count + '\" \/>' +\n            '<div class=\"io_video_play_icon\"><i class=\"fas fa-play-circle\"><\/i><\/div>' +\n          '<\/div>'\n        );\n\n        thumb.find('img').on('click', function()\n        {\n          ioRentalShowVideo(this);\n        });\n\n        thumbbox.append(thumb);\n      }\n      else if (media.rentalimage_imageloc)\n      {\n        var thumb = jQuery(\n          '<img class=\"io_image_thumb skip-lazy\" ' +\n          'title=\"' + rental_name_template + '\" ' +\n          'src=\"' + media.rentalimage_imageloc + '\" ' +\n          'alt=\"' + alt_text_template + '\" ' +\n          'data-big=\"' + media.rentalimage_imagelocbig + '\" ' +\n          'data-media-type=\"image\" ' +\n          'id=\"io_img_thumb' + count + '\" \/>'\n        );\n\n        thumb.on('click', function()\n        {\n          ioRentalShowImage(this);\n        });\n\n        thumbbox.append(thumb);\n      }\n    }\n\n    \/\/ Build FancyBox gallery array from images for #single_image click only\n    var fancyboxImages = [];\n    for (var fkey in images_arr)\n    {\n      var fmedia = images_arr[fkey];\n      if (fmedia.media_type !== 'video' && fmedia.rentalimage_imagelocbig)\n      {\n        fancyboxImages.push({ href: fmedia.rentalimage_imagelocbig, title: rental_name_template });\n      }\n    }\n\n    if (fancyboxImages.length && (window.innerWidth > 500 || window.location.href.indexOf(\"io_\") > -1) && window.location.href.indexOf(\"io_contactform\") == -1)\n    {\n      jQuery('#single_image').off('click.fancybox').on('click', function(e)\n      {\n        e.preventDefault();\n        e.stopPropagation();\n        var currentHref = jQuery(this).attr('href');\n        var startIndex = 0;\n        for (var fi = 0; fi < fancyboxImages.length; fi++)\n        {\n          if (fancyboxImages[fi].href === currentHref)\n          {\n            startIndex = fi;\n            break;\n          }\n        }\n        jQuery.fancybox.open(fancyboxImages,\n        {\n          \"transitionIn\": \"none\",\n          \"transitionOut\": \"none\",\n          \"titlePosition\": \"over\",\n          \"cyclic\": true,\n          index: startIndex,\n          helpers: {title: { type: \"over\"}},\n          beforeShow: function () { this.title = (this.title ? \"\" + this.title + \"\" : \"\") + \"Image \" + (this.index +1) + \" of \" + this.group.length; }\n        });\n      });\n    }\n    else\n    {\n      let imageClick = document.querySelector(\".io_product_picbox a#single_image\");\n      if (imageClick != undefined || imageClick != null) imageClick.addEventListener(\"click\", (e) => {e.preventDefault();});\n    }\n  });\n\n  function updatePageUpsell(data){\n    let page_carousel = jQuery(\".page-carousel\");\n    data.forEach(function(upsell){\n      cell = createPageCarouselCell(upsell[\"image\"], upsell[\"name\"], upsell[\"page\"], upsell[\"rental_id\"]);\n      page_carousel.append(cell);\n    });\n    makeCarousel(page_carousel);\n    setTimeout(pageFlickityRefresh, 500);\n    if(io_upsell_price == \"on\"){\n      let times = getAvailTimes();\n      let upsell_rental_id_str = getUpsellIDforPrice();\n      let return_id = 0;\n      let rental_names = \"off\";\n      if(upsell_rental_id_str != \"\"){\n        checkAvailCall(times[0],times[1],times[2],rental_names,upsell_rental_id_str,displayUpsellPrices,0,[],[],return_id,0,null,1,\"\",1);\n      }\n    }\n  }\n  function createPageCarouselCell(image, name, page, rental_id){\n    cell = `<div class=\"io_page_carousel_cell\"> <a href=\"`+page+`\" class=\"page-carousel-link\"> <img decoding=\"async\" class=\"page-carousel-image skip-lazy\" src=\"`+image+`\"> <p class=\"page-carousel-name\"> `+name+` <\/p> <span class=\"page-carousel-rid\" id=\"rid`+rental_id+`\" style=\"display:none\">`+rental_id+`<\/span> <\/a> <\/div>`;\n    return cell;\n  }\n  function pageFlickityRefresh(){\n    jQuery(\".page-carousel\").flickity(\"resize\");\n  }\n  function order_acc_obj_relate(){\n    let new_acc_obj_relate = new Map();\n    if(!jQuery.isEmptyObject(acc_obj_relate) && !jQuery.isEmptyObject(acc_obj_order)){\n      for(const [index, rid] of Object.entries(acc_obj_order)){\n        new_acc_obj_relate.set(rid, acc_obj_relate[rid])\n      }\n    }\n    return new_acc_obj_relate\n  }\n  \/* if an item is consumable IO-21288*\/\n  if(jQuery(\".item_qtytype\")[0].innerText == \"Supply\"){\n    jQuery(\"#io_all_prices\").hide();\n    jQuery(\".io_product_price_fixed\").show();\n  }\n<\/script><!-- End Shortcoder content -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":29597,"parent":5334,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"io_meta_description":"","footnotes":""},"class_list":["post-7635","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/pages\/7635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/comments?post=7635"}],"version-history":[{"count":94,"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/pages\/7635\/revisions"}],"predecessor-version":[{"id":85577,"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/pages\/7635\/revisions\/85577"}],"up":[{"embeddable":true,"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/pages\/5334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/media\/29597"}],"wp:attachment":[{"href":"https:\/\/www.aspartyrental.com\/lexington\/wp-json\/wp\/v2\/media?parent=7635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}